{"id":28,"count":1,"description":"Public and private extension systems, agent ratios and the cost of holding them.","link":"https:\/\/hagrotrading.com\/briefings\/tag\/agricultural-extension\/","name":"agricultural extension","slug":"agricultural-extension","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/hagrotrading.com\/briefings\/wp-json\/wp\/v2\/tags\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hagrotrading.com\/briefings\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/hagrotrading.com\/briefings\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/hagrotrading.com\/briefings\/wp-json\/wp\/v2\/posts?tags=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}